{"id":17661,"date":"2017-12-13T14:47:54","date_gmt":"2017-12-13T22:47:54","guid":{"rendered":"http:\/\/affirmation.org\/?p=17661"},"modified":"2021-10-03T10:05:08","modified_gmt":"2021-10-03T16:05:08","slug":"mormon-homosexuality-progress-1981","status":"publish","type":"post","link":"https:\/\/affirmation.org\/pt\/mormon-homossexualidade-progresso-1981\/","title":{"rendered":"At\u00e9 que ponto a Igreja M\u00f3rmon alcan\u00e7ou a homossexualidade desde 1981?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17664\" src=\"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\" alt=\"Guia do l\u00edder sobre capa de homossexualidade de 1981\" width=\"1200\" height=\"628\" srcset=\"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg 1200w, https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover-300x157.jpg 300w, https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover-768x402.jpg 768w, https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover-1024x536.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><strong>Por Joel McDonald<\/strong><\/p>\n<p>Em 12 de dezembro de 2017, <a href=\"https:\/\/mormonleaks.io\/\">Mormon Leaks<\/a> lan\u00e7ou um guia de 1981 para os l\u00edderes locais do sacerd\u00f3cio SUD sobre como lidar com a homossexualidade entre os membros da Igreja. Este guia n\u00e3o representa mais a vis\u00e3o oficial da Igreja SUD. Apesar do fato de a Igreja hoje ter renunciado explicitamente a algumas das posi\u00e7\u00f5es encontradas no guia (como que homossexualidade \u00e9 um comportamento aprendido ou uma escolha pecaminosa e pode ser curada), essas cren\u00e7as ainda s\u00e3o comuns entre os l\u00edderes e membros da Igreja SUD. Muitos membros da comunidade LGBT M\u00f3rmon experimentaram traumas como resultado das pr\u00e1ticas promovidas por este guia de 1981, e se voc\u00ea sentir que pode ser acionado por se expor \u00e0 linguagem e cren\u00e7as neste guia - muitas das quais a Igreja n\u00e3o endossa mais - n\u00e3o recomendamos a leitura. No entanto, revisar o que a Igreja estava dizendo em 1981, e comparar e contrastar com o que a Igreja est\u00e1 dizendo agora mostra quanta mudan\u00e7a positiva ocorreu para os m\u00f3rmons LGB desde 1981. Ele destaca a import\u00e2ncia das maneiras como a Afirma\u00e7\u00e3o continua seus 40+ anos de trabalho para promover uma maior compreens\u00e3o dos m\u00f3rmons LGBTQ + e suas fam\u00edlias e amigos e para promover mudan\u00e7as positivas dentro da comunidade m\u00f3rmon em geral.<\/p>\n<h2>A homossexualidade \u00e9 uma escolha? Como em?<\/h2>\n<p>\u201cHomossexualidade \u00e9 contato er\u00f3tico ou f\u00edsico ou atra\u00e7\u00e3o entre membros do mesmo sexo\u201d, o guia de 1981 informou os l\u00edderes. \u201cPode incluir pensamentos ou atra\u00e7\u00f5es emocionais sem comportamento sexual externo.\u201d Aqui vemos que, na \u00e9poca em que este guia foi produzido, a Igreja n\u00e3o distinguia pensamentos homossexuais de a\u00e7\u00f5es homossexuais. Quando o guia continua informando aos l\u00edderes que \u201ca homossexualidade \u00e9 um pecado\u201d, que \u201cqualquer racionaliza\u00e7\u00e3o da homossexualidade \u00e9 errada\u201d, nenhuma distin\u00e7\u00e3o \u00e9 feita entre atra\u00e7\u00e3o e agir de acordo com essa atra\u00e7\u00e3o. Aqui, talvez tenhamos a mudan\u00e7a mais significativa na maneira como a Igreja entende e instrui os l\u00edderes sobre homossexualidade entre 1981 e hoje.<\/p>\n<p>Hoje, a Igreja SUD tem o cuidado de fazer a distin\u00e7\u00e3o entre homossexualidade, ou atra\u00e7\u00e3o pelo mesmo sexo, e agir de acordo com essa atra\u00e7\u00e3o. Em 2012, a igreja lan\u00e7ou <a href=\"https:\/\/mormonsandgays.org\" target=\"_blank\" rel=\"noopener\">mormonsandgays.org<\/a>\u00a0onde foi afirmado pela primeira vez que &quot;os indiv\u00edduos n\u00e3o optam por ter essas atra\u00e7\u00f5es.&quot; Na verdade, a Igreja SUD, ao ter essa declara\u00e7\u00e3o em um site que eles criaram, estava informando ao mundo que sua compreens\u00e3o da homossexualidade agora inclu\u00eda uma distin\u00e7\u00e3o entre atra\u00e7\u00e3o e a\u00e7\u00e3o. Se a atra\u00e7\u00e3o pelo mesmo sexo n\u00e3o fosse uma escolha, n\u00e3o poderia ser um pecado. Hoje, o site da igreja, <a href=\"https:\/\/mormonandgay.lds.org\/\" target=\"_blank\" rel=\"noopener\">M\u00f3rmon e gay<\/a>, afirma que &quot;sentimentos de atra\u00e7\u00e3o pelo mesmo sexo n\u00e3o s\u00e3o um pecado.&quot;<\/p>\n<h2>O que causa a homossexualidade?<\/h2>\n<p>Antes de discutir brevemente o que a Igreja M\u00f3rmon via como as causas da homossexualidade em 1981, acho importante lembrar o que a comunidade m\u00e9dica via como as causas da homossexualidade nessa \u00e9poca. At\u00e9 1973, a homossexualidade era vista como um transtorno mental pela American Psychiatric Association. A Organiza\u00e7\u00e3o Mundial de Sa\u00fade n\u00e3o declarou a homossexualidade como um transtorno mental at\u00e9 1990. A vis\u00e3o da Igreja sobre a homossexualidade e suas causas estavam intimamente alinhadas com o entendimento geral da homossexualidade na comunidade m\u00e9dica e no p\u00fablico. O guia de 1981 informa aos l\u00edderes que a homossexualidade foi causada por um &quot;hist\u00f3rico familiar perturbado&quot;, &quot;relacionamento ruim com os colegas&quot;, &quot;atitudes sexuais n\u00e3o saud\u00e1veis&quot; e &quot;experi\u00eancia homossexual precoce&quot;, incluindo &quot;experi\u00eancias iniciais de masturba\u00e7\u00e3o&quot; ou &quot;introdu\u00e7\u00e3o \u00e0 experi\u00eancia homossexual por algu\u00e9m da sua idade ou alguns anos mais velho. \u201d<\/p>\n<p>Hoje, a Igreja SUD n\u00e3o faz nenhuma tentativa de definir as causas da homossexualidade. No <a href=\"https:\/\/mormonandgay.lds.org\/articles\/church-teachings?lang=eng\" target=\"_blank\" rel=\"noopener\">Site m\u00f3rmon e gay<\/a>, \u00c9 citado o \u00c9lder Dalin H. Oaks dizendo: \u201cA Igreja n\u00e3o tem uma posi\u00e7\u00e3o sobre as causas de nenhuma dessas suscetibilidades ou inclina\u00e7\u00f5es, incluindo aquelas relacionadas \u00e0 atra\u00e7\u00e3o pelo mesmo sexo\u201d. Isso \u00e9 significativo. \u201cToda a premissa deste panfleto \u00e9 que os homossexuais s\u00e3o quebrantados e est\u00e3o em desacordo com Deus\u201d, disse Ron Raynes, membro do Conselho da Afirma\u00e7\u00e3o. Esta n\u00e3o \u00e9 mais a vis\u00e3o da homossexualidade. Pessoas LGB n\u00e3o est\u00e3o quebradas e s\u00e3o &quot;filhos e filhas de Deus&quot;, de acordo com <a href=\"https:\/\/mormonandgay.lds.org\/articles\/church-teachings?lang=eng\" target=\"_blank\" rel=\"noopener\">M\u00f3rmon e Gay: Ensinamentos da Igreja<\/a>. No m\u00eas passado, <a href=\"https:\/\/affirmation.org\/pt\/ballard-answers-lgbt-questions-byu-devotional\" target=\"_blank\" rel=\"noopener\">O \u00c9lder M. Russell Ballard compartilhou sua cren\u00e7a<\/a> que membros gays e l\u00e9sbicas da igreja \u201ctenham um lugar no reino e reconhe\u00e7am que \u00e0s vezes pode ser dif\u00edcil para voc\u00ea ver onde se encaixa na Igreja do Senhor, mas voc\u00ea se encaixa\u201d.<\/p>\n<h2>A homossexualidade pode ser mudada? Curado?<\/h2>\n<p>Se a comunidade m\u00e9dica na \u00e9poca estava no meio de uma transi\u00e7\u00e3o de considerar a homossexualidade como um transtorno mental, eles tamb\u00e9m estavam deixando de considerar a homossexualidade como algo que poderia ser tratado e possivelmente curado. Este foi um debate significativo ao longo do s\u00e9culo XIX e XX. N\u00e3o surpreendentemente, a igreja instruiu os l\u00edderes locais que a homossexualidade era algo que poderia ser mudado. \u201cA quantidade de ajuda que voc\u00ea, como l\u00edder do sacerd\u00f3cio, pode prestar depende da disposi\u00e7\u00e3o e do desejo da pessoa de mudar. A pessoa deve se arrepender de seu comportamento homossexual e control\u00e1-lo aprendendo outros modos de vida. \u201d<\/p>\n<p>Os l\u00edderes do sacerd\u00f3cio foram incentivados a aconselhar os homossexuais em parte ajudando-os a estabelecer metas espirituais, sociais, f\u00edsicas e de autodisciplina. Os objetivos sociais s\u00e3o aqueles que talvez tenham sido os mais prejudiciais para os membros LGB, pois eles foram encorajados a &quot;estar em situa\u00e7\u00f5es apropriadas com o sexo oposto, mesmo que ele tenha que se for\u00e7ar&quot;, &quot;come\u00e7ar a namorar e aumentar gradualmente a frequ\u00eancia&quot; e imitar &quot; pap\u00e9is e pr\u00e1ticas masculinos ou femininos apropriados. \u201d Embora o guia n\u00e3o instrua explicitamente os l\u00edderes a encorajar membros gays e l\u00e9sbicas a se casarem com o sexo oposto, a se\u00e7\u00e3o final do guia diz: \u201cMuitos testemunhos escritos foram coletados de pessoas que superaram problemas homossexuais e encontraram paz e sucesso no namoro , casamento e atividades na Igreja \u201d. O casamento com o sexo oposto era o objetivo l\u00f3gico para os homossexuais transformados na igreja em 1981.<\/p>\n<p>\u201cTudo neste manual de 1981 flui da suposi\u00e7\u00e3o declarada desde o in\u00edcio de que a homossexualidade \u00e9 algo aprendido ou escolhido\u201d, compartilhou o Diretor Executivo da Afirma\u00e7\u00e3o, John Gustav-Wrathall. \u201cQuando essa \u00e9 a sua premissa, o resultado \u00e9 uma pr\u00e1tica terr\u00edvel. Os l\u00edderes foram, na verdade, aconselhados a responder com &#039;disciplina severa&#039; se a pessoa gay sendo aconselhada fosse percebida como tendo uma &#039;atitude rebelde&#039;, o que pode ser qualquer situa\u00e7\u00e3o envolvendo o aconselhamento de membros gays, j\u00e1 que o manual sugere que o mero fato de ser gay pode ser um sinal de rebeldia. N\u00e3o \u00e9 surpresa que o manual aconselhe uma abordagem completamente estruturada em torno da &#039;terapia de convers\u00e3o&#039; \u201d.<\/p>\n<p>Hoje, um casamento de orienta\u00e7\u00e3o mista n\u00e3o \u00e9 visto como resultado da mudan\u00e7a ou cura de homossexuais e n\u00e3o \u00e9 recomendado como uma solu\u00e7\u00e3o para membros LGB. O \u00c9lder Dalin H. Oaks em 2015 declarou que os l\u00edderes \u201cdefinitivamente n\u00e3o recomendam o casamento como uma solu\u00e7\u00e3o para os sentimentos do mesmo sexo. N\u00e3o, n\u00e3o \u00e9 uma terapia. Em tempos passados, d\u00e9cadas atr\u00e1s, havia algumas pr\u00e1ticas nesse sentido. N\u00f3s os erradicamos na Igreja agora. \u201d A igreja n\u00e3o desencoraja necessariamente o casamento de orienta\u00e7\u00e3o mista se o casal envolvido acredita que \u00e9 a melhor decis\u00e3o para eles e n\u00e3o \u00e9 feito sob falsos pretextos.<\/p>\n<p>o <a href=\"https:\/\/mormonandgay.lds.org\/articles\/frequently-asked-questions?lang=eng\" target=\"_blank\" rel=\"noopener\">Site de gays e m\u00f3rmons<\/a> afirma que \u201ca intensidade da atra\u00e7\u00e3o pelo mesmo sexo n\u00e3o \u00e9 uma medida de sua fidelidade. Muitas pessoas oram por anos e fazem tudo o que podem para ser obedientes em um esfor\u00e7o para reduzir a atra\u00e7\u00e3o pelo mesmo sexo, mas descobrem que ainda se sentem atra\u00eddas pelo mesmo sexo. \u201d A igreja n\u00e3o parece interessada nas pessoas que tentam mudar suas atra\u00e7\u00f5es, mas continua preocupada se os membros agem de acordo com essas atra\u00e7\u00f5es. \u201cA intensidade de suas atra\u00e7\u00f5es pode n\u00e3o estar sob seu controle; no entanto, voc\u00ea pode escolher como responder. \u201d<\/p>\n<h2>A persist\u00eancia de ideias prejudiciais<\/h2>\n<p>Oficialmente, o que a Igreja SUD entende e ensina sobre homossexualidade pode ter mudado em 40 anos e, com sorte, continuar\u00e1 a mudar de forma positiva para os membros LGB (e transg\u00eaneros). Infelizmente, ideias antigas e prejudiciais ainda persistem entre os membros da igreja e l\u00edderes locais.<\/p>\n<p>\u201cEm fevereiro \/ mar\u00e7o de 2016, os l\u00edderes locais ainda incentivavam os casamentos de orienta\u00e7\u00e3o mista\u201d, compartilhou Sarah Broat. \u201cFoi ent\u00e3o que ocorreu o cancelamento do selamento com meu ex-marido, e meu bispo imediatamente me incentivou a come\u00e7ar a procurar um novo, sabendo que sou l\u00e9sbica. Tamb\u00e9m me disseram que eu seria &#039;f\u00edsica e espiritualmente destru\u00eddo&#039; por n\u00e3o acreditar que a homossexualidade era apostasia. \u201d<\/p>\n<p>\u201cEste guia explica muito. Essas ideias persistiram pelo menos durante o ano de 2001, quando me inscrevi para a BYU. Quando falei com meu bispo no final de 2000, ele seguiu muitas das diretrizes e comentou que havia sido treinado recentemente sobre como lidar com membros que lutam contra a homossexualidade \u201d, compartilhou Alexander Shafer. \u201cO bispo e o terapeuta me disseram que a din\u00e2mica familiar era respons\u00e1vel por meus sentimentos homossexuais e que eu poderia ser curado. Posso ver claramente agora que essas ideias influenciaram minha decis\u00e3o de me casar com algu\u00e9m do sexo oposto e voltar para o arm\u00e1rio at\u00e9 recentemente. \u201d<\/p>\n<p>A Afirma\u00e7\u00e3o est\u00e1 trabalhando para dissipar essas id\u00e9ias prejudiciais, fornecendo <a href=\"https:\/\/affirmation.org\/pt\/lideres-da-igreja-2\" target=\"_blank\" rel=\"noopener\">recursos e treinamento para l\u00edderes SUD locais que buscam cuidar de membros LGBT em suas alas e ramos<\/a>. Desde 2015, uma trilha para l\u00edderes foi inclu\u00edda na Confer\u00eancia Anual de Afirma\u00e7\u00e3o.<\/p>\n<h2>Progresso n\u00e3o perfeito<\/h2>\n<p>Ao olhar para onde a Igreja estava em 1981 destaca um progresso significativo, ainda h\u00e1 muito progresso a ser feito. Faltando completamente nesta discuss\u00e3o est\u00e3o os desafios que os m\u00f3rmons transg\u00eaneros enfrentam na igreja. E \u00e9 imposs\u00edvel n\u00e3o fazer refer\u00eancia \u00e0 dor e ao trauma que se seguiram ao <a href=\"https:\/\/affirmation.org\/pt\/tag\/november-2015-policy\" target=\"_blank\" rel=\"noopener\">mudan\u00e7as de pol\u00edtica de novembro de 2015<\/a>. Ainda assim, o guia \u00e9 um testemunho da mudan\u00e7a positiva que ocorreu desde quando foi publicado em 1981 e um lembrete de que mudan\u00e7as futuras s\u00e3o poss\u00edveis.<\/p>","protected":false},"excerpt":{"rendered":"<p>Um recente lan\u00e7amento do Mormon Leaks nos lembrou de como os l\u00edderes locais da Igreja M\u00f3rmon foram aconselhados a abordar a homossexualidade e aconselhar membros gays e l\u00e9sbicas em 1981. Quanto, se alguma coisa, mudou desde ent\u00e3o?<\/p>","protected":false},"author":25,"featured_media":17664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_piecal_is_recurring":false,"_piecal_recurring_interval":1,"_piecal_recurring_frequency":"","_piecal_recurring_exact_position":false,"_piecal_recurring_end":"","_piecal_color":"","_piecal_text_color":"","_piecal_global_color_master":false,"_piecal_rsets":"[]","_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"footnotes":""},"categories":[1849],"tags":[375,324,19,1247],"newsletters":[],"class_list":["post-17661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-church-leaders","tag-leaders","tag-leadership","tag-mormon-leaks"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How Far has the Mormon Church Come on Homosexuality Since 1981?<\/title>\n<meta name=\"description\" content=\"How much, if anything, has changed in the way local leaders in the Mormon Church are advised to address homosexuality and counsel gay and lesbian members?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/affirmation.org\/pt\/progreso-homosexualidad-mormona-1981\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Far has the Mormon Church Come on Homosexuality Since 1981?\" \/>\n<meta property=\"og:description\" content=\"How much, if anything, has changed in the way local leaders in the Mormon Church are advised to address homosexuality and counsel gay and lesbian members?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/affirmation.org\/pt\/progreso-homosexualidad-mormona-1981\" \/>\n<meta property=\"og:site_name\" content=\"Affirmation: LGBTQ Mormons, Families &amp; Friends\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AffirmationLGBTMormonsFamiliesFriends\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-13T22:47:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-03T16:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joel McDonald\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@affirmationLDS\" \/>\n<meta name=\"twitter:site\" content=\"@affirmationLDS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joel McDonald\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/\"},\"author\":{\"name\":\"Joel McDonald\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/#\\\/schema\\\/person\\\/af7c049f7b37ce3fd3f4b328d141ba9b\"},\"headline\":\"How Far has the Mormon Church Come on Homosexuality Since 1981?\",\"datePublished\":\"2017-12-13T22:47:54+00:00\",\"dateModified\":\"2021-10-03T16:05:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/\"},\"wordCount\":1574,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/affirmation.org\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\",\"keywords\":[\"Church Leaders\",\"Leaders\",\"Leadership\",\"Mormon Leaks\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/\",\"url\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/\",\"name\":\"How Far has the Mormon Church Come on Homosexuality Since 1981?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/affirmation.org\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\",\"datePublished\":\"2017-12-13T22:47:54+00:00\",\"dateModified\":\"2021-10-03T16:05:08+00:00\",\"description\":\"How much, if anything, has changed in the way local leaders in the Mormon Church are advised to address homosexuality and counsel gay and lesbian members?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#primaryimage\",\"url\":\"https:\\\/\\\/affirmation.org\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\",\"contentUrl\":\"https:\\\/\\\/affirmation.org\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/1981-Leader-Guide-on-Homosexuality-Cover.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/es\\\/progreso-homosexualidad-mormona-1981\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/affirmation.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Far has the Mormon Church Come on Homosexuality Since 1981?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/#website\",\"url\":\"https:\\\/\\\/affirmation.org\\\/\",\"name\":\"Affirmation: LGBTQ Mormons, Families &amp; Friends\",\"description\":\"Worldwide communities of safety, love, and hope.\",\"publisher\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/affirmation.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/#organization\",\"name\":\"Affirmation: LGBTQ Mormons, Families & Friends\",\"url\":\"https:\\\/\\\/affirmation.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Affirmation: LGBTQ Mormons, Families & Friends\"},\"image\":{\"@id\":\"https:\\\/\\\/affirmation.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AffirmationLGBTMormonsFamiliesFriends\\\/\",\"https:\\\/\\\/x.com\\\/affirmationLDS\",\"https:\\\/\\\/www.instagram.com\\\/affirmation.lds\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AffirmationLDS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/affirmation.org\\\/#\\\/schema\\\/person\\\/af7c049f7b37ce3fd3f4b328d141ba9b\",\"name\":\"Joel McDonald\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g\",\"caption\":\"Joel McDonald\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"At\u00e9 que ponto a Igreja M\u00f3rmon alcan\u00e7ou a homossexualidade desde 1981?","description":"O quanto, se alguma coisa, mudou na forma como os l\u00edderes locais da Igreja M\u00f3rmon s\u00e3o aconselhados a abordar a homossexualidade e aconselhar membros gays e l\u00e9sbicas?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/affirmation.org\/pt\/progreso-homosexualidad-mormona-1981","og_locale":"pt_BR","og_type":"article","og_title":"How Far has the Mormon Church Come on Homosexuality Since 1981?","og_description":"How much, if anything, has changed in the way local leaders in the Mormon Church are advised to address homosexuality and counsel gay and lesbian members?","og_url":"https:\/\/affirmation.org\/pt\/progreso-homosexualidad-mormona-1981","og_site_name":"Affirmation: LGBTQ Mormons, Families &amp; Friends","article_publisher":"https:\/\/www.facebook.com\/AffirmationLGBTMormonsFamiliesFriends\/","article_published_time":"2017-12-13T22:47:54+00:00","article_modified_time":"2021-10-03T16:05:08+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg","type":"image\/jpeg"}],"author":"Joel McDonald","twitter_card":"summary_large_image","twitter_creator":"@affirmationLDS","twitter_site":"@affirmationLDS","twitter_misc":{"Escrito por":"Joel McDonald","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#article","isPartOf":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/"},"author":{"name":"Joel McDonald","@id":"https:\/\/affirmation.org\/#\/schema\/person\/af7c049f7b37ce3fd3f4b328d141ba9b"},"headline":"How Far has the Mormon Church Come on Homosexuality Since 1981?","datePublished":"2017-12-13T22:47:54+00:00","dateModified":"2021-10-03T16:05:08+00:00","mainEntityOfPage":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/"},"wordCount":1574,"commentCount":2,"publisher":{"@id":"https:\/\/affirmation.org\/#organization"},"image":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#primaryimage"},"thumbnailUrl":"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg","keywords":["Church Leaders","Leaders","Leadership","Mormon Leaks"],"articleSection":["Blog"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/","url":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/","name":"At\u00e9 que ponto a Igreja M\u00f3rmon alcan\u00e7ou a homossexualidade desde 1981?","isPartOf":{"@id":"https:\/\/affirmation.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#primaryimage"},"image":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#primaryimage"},"thumbnailUrl":"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg","datePublished":"2017-12-13T22:47:54+00:00","dateModified":"2021-10-03T16:05:08+00:00","description":"O quanto, se alguma coisa, mudou na forma como os l\u00edderes locais da Igreja M\u00f3rmon s\u00e3o aconselhados a abordar a homossexualidade e aconselhar membros gays e l\u00e9sbicas?","breadcrumb":{"@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#primaryimage","url":"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg","contentUrl":"https:\/\/affirmation.org\/wp-content\/uploads\/2017\/12\/1981-Leader-Guide-on-Homosexuality-Cover.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/affirmation.org\/es\/progreso-homosexualidad-mormona-1981\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/affirmation.org\/"},{"@type":"ListItem","position":2,"name":"How Far has the Mormon Church Come on Homosexuality Since 1981?"}]},{"@type":"WebSite","@id":"https:\/\/affirmation.org\/#website","url":"https:\/\/affirmation.org\/","name":"Afirma\u00e7\u00e3o: M\u00f3rmons, fam\u00edlias e amigos LGBTQ","description":"Comunidades mundiais de seguran\u00e7a, amor e esperan\u00e7a.","publisher":{"@id":"https:\/\/affirmation.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/affirmation.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/affirmation.org\/#organization","name":"Afirma\u00e7\u00e3o: M\u00f3rmons LGBTQ, Fam\u00edlias e Amigos","url":"https:\/\/affirmation.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/affirmation.org\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Affirmation: LGBTQ Mormons, Families & Friends"},"image":{"@id":"https:\/\/affirmation.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AffirmationLGBTMormonsFamiliesFriends\/","https:\/\/x.com\/affirmationLDS","https:\/\/www.instagram.com\/affirmation.lds\/","https:\/\/www.youtube.com\/user\/AffirmationLDS"]},{"@type":"Person","@id":"https:\/\/affirmation.org\/#\/schema\/person\/af7c049f7b37ce3fd3f4b328d141ba9b","name":"Joel McDonald","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/75cb7baa3df7a4b72a5a6fff06884591403fc011bfd38b2b7cd54ba4503d0b30?s=96&d=mm&r=g","caption":"Joel McDonald"}}]}},"_links":{"self":[{"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/posts\/17661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/comments?post=17661"}],"version-history":[{"count":0,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/posts\/17661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/media\/17664"}],"wp:attachment":[{"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/media?parent=17661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/categories?post=17661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/tags?post=17661"},{"taxonomy":"newsletters","embeddable":true,"href":"https:\/\/affirmation.org\/pt\/wp-json\/wp\/v2\/newsletters?post=17661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}